{"id":7121,"date":"2024-03-06T14:05:02","date_gmt":"2024-03-06T13:05:02","guid":{"rendered":"https:\/\/nijar.org\/?p=7121"},"modified":"2024-03-07T20:59:53","modified_gmt":"2024-03-07T19:59:53","slug":"rivista-marzo-2024","status":"publish","type":"post","link":"https:\/\/nijar.org\/it\/rivista-marzo-2024","title":{"rendered":"Giornale marzo 2024"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Vivere nel Giardino di N\u00e2m<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iniziato con venti forti e un po' di pioggia, febbraio ha mostrato i primi segni della primavera in arrivo. La sera e nelle prime mattine fresche l'aria \u00e8 ancora fresca e occorre una giacca. Durante le meditazioni e nelle camere degli ospiti le stufe creano un'atmosfera confortevole. Siamo grati per il ritorno del sole che ci riscalda abbastanza bene durante la maggior parte della giornata. <\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-scaled.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-1024x768.jpeg\" alt=\"\" class=\"wp-image-7149\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-1024x768.jpeg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-300x225.jpeg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-768x576.jpeg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-1536x1152.jpeg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-2048x1536.jpeg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-16x12.jpeg 16w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5661-600x450.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">I sentieri del Giardino stanno assumendo una forma rinnovata, disegnando letteralmente un percorso piacevole e stabile per le passeggiate quotidiane di meditazione e per godere della bellezza e dei benefici del Giardino. Insieme ai sentieri, sono stati restaurati anche i muri della terrazza. \u00c8 sorprendente vedere il Giardino emergere come \u00e8 destinato a essere. \u00c8 come osservare un pittore mentre completa, lentamente ma inesorabilmente, l'opera d'arte che ha in mente. Solo che qui ci sono molti artisti diversi, che lavorano insieme su momenti diversi e danno forma a una variet\u00e0 di elementi che insieme esprimono il tutto.<\/p>\n\n\n\n<div style=\"height:0px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Uno di questi artisti ha soggiornato e vissuto per un mese nel Giardino di N\u00e2m, svolgendo un lavoro meditativo attraverso la co-costruzione di questi sentieri. \u00c8 riuscito anche a scrivere un bel pezzo sull'esperienza del suo soggiorno. Una bella storia che condividiamo con gratitudine in questa newsletter.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-scaled.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7134\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-1024x768.jpeg\" alt=\"\" class=\"wp-image-7134\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-1024x768.jpeg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-300x225.jpeg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-768x576.jpeg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-1536x1152.jpeg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-2048x1536.jpeg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-16x12.jpeg 16w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5592-600x450.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae.jpg\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"7135\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-1024x1024.jpg\" alt=\"\" class=\"wp-image-7135\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-1024x1024.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-300x300.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-150x150.jpg 150w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-768x768.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-1536x1536.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-12x12.jpg 12w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-600x600.jpg 600w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae-100x100.jpg 100w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/4396a740-5e05-489f-b407-bf3e9d6ef7ae.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" data-id=\"7127\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-1024x682.jpg\" alt=\"\" class=\"wp-image-7127\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-1024x682.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-300x200.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-768x512.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-18x12.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752-600x400.jpg 600w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000752.jpg 1300w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un gruppo internazionale di persone si \u00e8 unito al primo Ritiro del Silenzio di quest'anno solare. Abbiamo avuto il tutto esaurito. Dopo tutte le attivit\u00e0 delle settimane precedenti, nel Giardino di N\u00e2m \u00e8 emerso un silenzio completo che ci ha accompagnato con grazia per una settimana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siamo in attesa del primo Ritiro della Serenit\u00e0 di N\u00e2m, che inizier\u00e0 tra circa 2 settimane; un breve soggiorno meditativo che include gli HarpMood mattutini e serali con Yogin\u00e2m. Aprile sar\u00e0 un mese intenso, con un ritiro di Yoga, Sciamanesimo e Silenzio in arrivo. E Chris, il nostro progettista di giardini ecologici, ci metter\u00e0 al lavoro all'inizio del mese. Ma tutto questo appartiene a un'altra storia e potrete leggerlo a tempo debito. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per ora godetevi l'impressione di Peters. Per i nostri lettori olandesi abbiamo aggiunto il testo originale qui sotto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vi auguriamo un bellissimo inizio di stagione primaverile!<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7121_ee0325-3c .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-7121_ee0325-3c .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7121_ee0325-3c\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" data-id=\"7156\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-1024x512.jpg\" alt=\"\" class=\"wp-image-7156\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-1024x512.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-300x150.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-768x384.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-1536x768.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-2048x1024.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-18x9.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-1-600x300.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Per quasi un mese ho soggiornato nel Giardino di N\u00e2m e ho vissuto insieme ai residenti. Ho fatto una montagna di lavoro e sono uscito alcune volte a Nijar, Huebro e Almeria e ho partecipato a un ritiro silenzioso.<\/em><\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"7132\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-1024x1024.jpg\" alt=\"\" class=\"wp-image-7132\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-1024x1024.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-300x300.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-150x150.jpg 150w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-768x768.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-1536x1536.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-2048x2048.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-12x12.jpg 12w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-600x600.jpg 600w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163016-100x100.jpg 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-rotated.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"7133\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-1024x1024.jpg\" alt=\"\" class=\"wp-image-7133\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-1024x1024.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-300x300.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-150x150.jpg 150w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-768x768.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-1536x1536.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-2048x2048.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-12x12.jpg 12w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-600x600.jpg 600w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240212_123009-100x100.jpg 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"7131\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-1024x683.jpg\" alt=\"\" class=\"wp-image-7131\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-1024x683.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-300x200.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-768x512.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-1536x1024.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-2048x1365.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-18x12.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000658-1-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sentieri di sabbia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la mano mi asciugo il sudore dalla fronte. Il sole \u00e8 ben saldo nel cielo e assicura una temperatura gradevole per questo periodo dell'anno, febbraio; circa 20 gradi. Ho appena finito di caricare una carriola di sabbia da un enorme mucchio contro il muro vicino alla Triade. La sabbia deve essere spostata in alto nel Giardino di N\u00e2m. Passo dopo passo lungo i sentieri sabbiosi, passando davanti alle palme, ai cactus, ai campi di verdure, dove si coltivano diversi tipi di ortaggi, e supero la terrazza al centro del giardino. Mi fermo un attimo per godermi la vista della casa dello Yogin\u00e2m e delle montagne alle sue spalle. Sembra che il tempo rimarr\u00e0 bello per un po', perch\u00e9 c'\u00e8 un cielo azzurro e limpido. Vedo le mie impronte ovunque sui sentieri sterrati, in entrambe le direzioni, perch\u00e9 ho fatto avanti e indietro con la carriola diverse volte. Quando sento il rumore della betoniera, so che sono quasi arrivato a destinazione. Edwin \u00e8 impegnato a fare il cemento per il sentiero di sabbia che stiamo per ristrutturare in giardino. Scarico la sabbia su un grande mucchio gi\u00e0 presente. Jasper \u00e8 impegnato a rincalzare la sabbia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I sentieri di sabbia del Giardino di N\u00e2m sono in fase di ristrutturazione. Ci\u00f2 significa che i sentieri vengono rialzati, appiattiti e dotati di un bordo di pietre che vengono cementate nel cemento. \u00c8 un bel lavoro. Durante il mio soggiorno di quasi quattro settimane, \u00e8 stato costruito un nuovo sentiero di quaranta metri. Poich\u00e9 l'intero percorso del giardino \u00e8 lungo circa 800-900 metri, si prevede che non sar\u00e0 completato prima della fine dell'anno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Vita ricca<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trascorrere un periodo cos\u00ec lungo a Nijar mi d\u00e0 l'opportunit\u00e0 di vivere per un po' insieme ai residenti. Una vita ricca e stimolante. Trascorro l'intera giornata all'aperto, in giardino, o a volte esco per visitare posti bellissimi. Ci incontriamo tre volte al giorno nella sala di meditazione. Ogni giorno vengono preparati pasti deliziosi che gustiamo insieme in silenzio. Si pu\u00f2 fare un'intera lista di desideri per una vacanza che si vogliono realizzare, ma lasciar andare questi desideri e immergersi nella vita nel Giardino di N\u00e2m pu\u00f2 portare a una sensazione di vacanza molto migliore.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"7140\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-1024x1024.jpg\" alt=\"\" class=\"wp-image-7140\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-1024x1024.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-300x300.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-150x150.jpg 150w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-768x768.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-1536x1536.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-2048x2048.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-12x12.jpg 12w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-600x600.jpg 600w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/20240217_163319-100x100.jpg 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7141\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-1024x768.jpeg\" alt=\"\" class=\"wp-image-7141\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-1024x768.jpeg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-300x225.jpeg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-768x576.jpeg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-1536x1152.jpeg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-2048x1536.jpeg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-16x12.jpeg 16w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5550-600x450.jpeg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"7142\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-1024x683.jpg\" alt=\"\" class=\"wp-image-7142\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-1024x683.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-300x200.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-768x512.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-1536x1024.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-2048x1365.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-18x12.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000795-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fortezza moresca<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oltre a spostare la sabbia con le carriole, sono uscita diverse volte. In bicicletta e a piedi per Nijar, godendomi le stradine con le tipiche case bianche spagnole, spesso con porte e finestre dipinte con colori bellissimi. A Huebro, dopo un bel giro in auto tra le montagne, abbiamo attinto acqua potabile da un pozzo con una grande vasca. Ad Almeria abbiamo visitato l'enorme fortezza moresca, risalente all'XI secolo, con un'ampia vista sul porto. La zona non \u00e8 solo ricca di montagne e natura, ma anche di cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ritiro silenzioso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il momento culminante del mio soggiorno \u00e8 il ritiro silenzioso di cinque giorni in un gruppo di sette persone. Durante l'HarpMoods Yogin\u00e2m vi porta attraverso tutti i tipi di strati di esperienza. Pieno di compassione, il suono della sua arpa ti porta a uno stato d'essere che va oltre quello di io e del mondo. Un'esperienza di guarigione che ha lasciato una profonda impressione. Sono sicuro che risuoner\u00e0 per molto tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sorriso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo aver fatto le valigie per tornare nei Paesi Bassi, mi godo ancora una volta la splendida vista sul giardino e sulle montagne circostanti. Sorrido quando vedo la parte del sentiero rinnovato a cui ho potuto contribuire.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7121_22eae0-98 .kt-block-spacer{height:50px;}.wp-block-kadence-spacer.kt-block-spacer-7121_22eae0-98 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7121_22eae0-98\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-1024x512.jpg\" alt=\"\" class=\"wp-image-7158\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-1024x512.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-300x150.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-768x384.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-1536x768.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-2048x1024.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-18x9.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/Een-subtitel-toevoegen-Middelgrote-banner-VS-liggend-2-600x300.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Per un anno sono stato nel Giardino di N\u00e2m. Ho lavorato con i miei compagni, ho scoperto un posto di lavoro e sono andato per un paio di giorni a Nijar, Huebro e Almeria e ho dato il mio nome a una casa di riposo.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Zandpaden<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la mia mano vedo la strada dolcemente aperta dal mio giardino. La zona si trova vicino all'albero e nel periodo di quest'anno, il mese di febbraio, ha una temperatura di circa 20 gradi. Ho una macchina da corsa pronta con un enorme cerchio che si trova davanti al muso, vicino alla triade. Il suo nastro deve essere rimosso da qui nel Giardino di N\u00e2m. Faccio un giro su questo sentiero tra le palme, i cactus, le brughiere, dove si trovano tutti gli ortaggi, e le terrazze nel giardino. Mi fermo anche per godermi la vista della casa di Yogin\u00e2m e dei suoi ospiti. Il luogo in cui si trova la casa non \u00e8 molto bello, perch\u00e9 c'\u00e8 un'anima stretta. In generale, sul pannello di controllo ci sono le mie tasche personali, in due dimensioni, ma ho bisogno di un po' di tempo per fare un po' di fatica con la carrozza. Als ik het geluid van de betonmolen hoor weet ik dat ik bijna bij mijn eindbestemming ben. Edwin si preoccupa di preparare il beton per la zanzariera che abbiamo lasciato nel cortile a verniciare. Ho spostato lo zand su un grande masso che si trova in zona. Jasper \u00e8 molto gentile nel timbrare il cartellino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I padiglioni del Giardino di N\u00e2m sono stati rinnovati. Ci\u00f2 significa che i padiglioni sono aperti, ricoperti di piastre e sono coperti da una serie di stenelle che, con l'aiuto della betonera, sono molto pi\u00f9 grandi di quanto si possa immaginare. Si tratta di un'ottima scelta. Durante il mio soggiorno di due settimane, \u00e8 stato cambiato un nuovo cuscinetto per diversi metri. Dato che l'unica piazzola in casa \u00e8 lunga tra gli 800 e i 900 metri, \u00e8 da tenere presente che il passo successivo in questo periodo \u00e8 ancora in corso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rijk leven<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il lungo periodo trascorso a Nijar mi ha dato la possibilit\u00e0 di vivere un periodo in comune con gli ospiti. Un'esperienza stimolante e divertente. L'ultimo giorno sono rimasto nella tenda o ho aperto un tavolo per vedere delle belle piazze. Per tre giorni siamo stati a meditare. Ogni giorno ci sono delle bellissime palestre in cui possiamo godere di un'atmosfera rilassata e rilassante. \u00c8 possibile creare un'unica lista di pensieri che si vuole controllare, ma la perdita di questi pensieri e l'apertura della vita nel Giardino di N\u00e2m non sono un problema, anzi, sono molto pi\u00f9 interessanti di quelli che si possono ottenere con una vakantie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Forte dei Mori<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo aver visto la presenza di zand nelle carrozze, ho trovato un'infinit\u00e0 di keren in giro. A Nijar, in mezzo a piccole stradine con tipiche case di campagna spagnole, con bellissimi giardini e raamlijsten. A Huebro, dopo un'incantevole passeggiata verso le baie, si pu\u00f2 bere l'acqua delle baie in un grande bacino. Ad Almeria si trova anche l'enorme forte Moorse, nato negli ultimi anni del secolo scorso e con un'ottima vista sull'oasi. La zona non \u00e8 solo ricca di natura e flora, ma anche di cultura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Stilteretraite<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il punto di partenza della mia vita verbale \u00e8 il viaggio a piedi, in un gruppo di sette persone, con Yogin\u00e2m. Durante gli Harpmoods, egli mi invita a fare il bagno in tutti gli aspetti della vita. Le corde della sua arpa la conducono, con compassione, verso uno stadio della vita che \u00e8 pi\u00f9 importante di quello che ha il mondo. \u00c8 un'esperienza di grande aiuto, che pu\u00f2 creare un forte malcontento e che pu\u00f2 essere sfruttata. Quando ho ricevuto le mie offerte per partire verso i Paesi Bassi, mi sono goduto un'altra volta l'incantevole vista sul mare e sulle isole. Mi piace quando mi si apre il pad di casa, dove ho trovato un'altra sistemazione.<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-1024x683.jpg\" alt=\"\" class=\"wp-image-7164\" srcset=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-1024x683.jpg 1024w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-300x200.jpg 300w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-768x512.jpg 768w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-1536x1024.jpg 1536w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-2048x1365.jpg 2048w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-18x12.jpg 18w, https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/P1000791-2-600x400.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Vivere nel Giardino di N\u00e2m A partire da venti forti e un po' di pioggia, febbraio ha mostrato i primi segni della primavera in arrivo. La sera e nelle prime mattine fresche l'aria \u00e8 ancora fresca e occorre una giacca. Durante le meditazioni e nelle stanze degli ospiti le stufe creano un'atmosfera confortevole....<\/p>","protected":false},"author":5,"featured_media":7126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-the-monthly-journal"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"katrin.brait\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/nijar.org\/it\/rivista-marzo-2024\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"The Garden of N\u00e2m ~ Retreat &amp; Meditation Center - Meditation Centre with Guest Rooms in Andalusia\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Journal March 2024 - The Garden of N\u00e2m ~ Retreat &amp; Meditation Center\" \/>\n\t\t<meta property=\"og:description\" content=\"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/nijar.org\/it\/rivista-marzo-2024\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-03-06T13:05:02+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-07T19:59:53+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/thegardenofnam\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Journal March 2024 - The Garden of N\u00e2m ~ Retreat &amp; Meditation Center\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#blogposting\",\"name\":\"Journal March 2024 - The Garden of N\\u00e2m ~ Retreat & Meditation Center\",\"headline\":\"Journal March 2024\",\"author\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/author\\\/katrin-brait#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nijar.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_5582.jpeg\",\"width\":1300,\"height\":975},\"datePublished\":\"2024-03-06T14:05:02+01:00\",\"dateModified\":\"2024-03-07T20:59:53+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#webpage\"},\"articleSection\":\"The Monthly Journal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nijar.org\\\/it\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/categoria\\\/il-mensile-giornale#listItem\",\"name\":\"The Monthly Journal\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/categoria\\\/il-mensile-giornale#listItem\",\"position\":2,\"name\":\"The Monthly Journal\",\"item\":\"https:\\\/\\\/nijar.org\\\/it\\\/categoria\\\/il-mensile-giornale\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#listItem\",\"name\":\"Journal March 2024\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#listItem\",\"position\":3,\"name\":\"Journal March 2024\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/categoria\\\/il-mensile-giornale#listItem\",\"name\":\"The Monthly Journal\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/#organization\",\"name\":\"N\\u00e2m Foundation\",\"description\":\"N\\u00e2m Foundation is a volunteer-run nonprofit organisation, committed to sharing the pure and open message of LivingN\\u00e2m.\",\"url\":\"https:\\\/\\\/nijar.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nijar.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/nijar-logo-2024.png\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024\\\/#organizationLogo\",\"width\":974,\"height\":204},\"image\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/thegardenofnam\",\"https:\\\/\\\/www.instagram.com\\\/the_garden_of_nam\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/author\\\/katrin-brait#author\",\"url\":\"https:\\\/\\\/nijar.org\\\/it\\\/author\\\/katrin-brait\",\"name\":\"katrin.brait\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e7855f89a15fccf1723a4c1e0baa027ad2d626c5d46442f8522f2338dbd8a2e?s=96&d=mm&r=g\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#webpage\",\"url\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024\",\"name\":\"Journal March 2024 - The Garden of N\\u00e2m ~ Retreat & Meditation Center\",\"description\":\"Living in the Garden of N\\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/author\\\/katrin-brait#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/author\\\/katrin-brait#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/nijar.org\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/IMG_5582.jpeg\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024\\\/#mainImage\",\"width\":1300,\"height\":975},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/rivista-marzo-2024#mainImage\"},\"datePublished\":\"2024-03-06T14:05:02+01:00\",\"dateModified\":\"2024-03-07T20:59:53+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/nijar.org\\\/it\\\/\",\"name\":\"The Garden of N\\u00e2m ~ Retreat & Meditation Center\",\"description\":\"Meditation Centre with Guest Rooms in Andalusia\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/nijar.org\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Journal March 2024 - The Garden of N\u00e2m ~ Retreat &amp; Meditation Center<\/title>\n\n","aioseo_head_json":{"title":"Diario Marzo 2024 - Il Giardino di N\u00e2m ~ Centro di ritiro e meditazione","description":"Vivere nel Giardino di N\u00e2m A partire da venti forti e un po' di pioggia, febbraio ha mostrato i primi segni della primavera in arrivo. La sera e nelle prime mattine fresche l'aria \u00e8 ancora fresca e occorre una giacca. Durante le meditazioni e nelle stanze degli ospiti le stufe creano un'atmosfera confortevole.","canonical_url":"https:\/\/nijar.org\/it\/rivista-marzo-2024","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#blogposting","name":"Journal March 2024 - The Garden of N\u00e2m ~ Retreat & Meditation Center","headline":"Journal March 2024","author":{"@id":"https:\/\/nijar.org\/it\/author\/katrin-brait#author"},"publisher":{"@id":"https:\/\/nijar.org\/it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5582.jpeg","width":1300,"height":975},"datePublished":"2024-03-06T14:05:02+01:00","dateModified":"2024-03-07T20:59:53+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#webpage"},"isPartOf":{"@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#webpage"},"articleSection":"The Monthly Journal"},{"@type":"BreadcrumbList","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/nijar.org\/it#listItem","position":1,"name":"Home","item":"https:\/\/nijar.org\/it","nextItem":{"@type":"ListItem","@id":"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale#listItem","name":"The Monthly Journal"}},{"@type":"ListItem","@id":"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale#listItem","position":2,"name":"The Monthly Journal","item":"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale","nextItem":{"@type":"ListItem","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#listItem","name":"Journal March 2024"},"previousItem":{"@type":"ListItem","@id":"https:\/\/nijar.org\/it#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#listItem","position":3,"name":"Journal March 2024","previousItem":{"@type":"ListItem","@id":"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale#listItem","name":"The Monthly Journal"}}]},{"@type":"Organization","@id":"https:\/\/nijar.org\/it\/#organization","name":"N\u00e2m Foundation","description":"N\u00e2m Foundation is a volunteer-run nonprofit organisation, committed to sharing the pure and open message of LivingN\u00e2m.","url":"https:\/\/nijar.org\/it\/","logo":{"@type":"ImageObject","url":"https:\/\/nijar.org\/wp-content\/uploads\/2023\/01\/nijar-logo-2024.png","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024\/#organizationLogo","width":974,"height":204},"image":{"@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/thegardenofnam","https:\/\/www.instagram.com\/the_garden_of_nam\/"]},{"@type":"Person","@id":"https:\/\/nijar.org\/it\/author\/katrin-brait#author","url":"https:\/\/nijar.org\/it\/author\/katrin-brait","name":"katrin.brait","image":{"@type":"ImageObject","url":"https:\/\/secure.gravatar.com\/avatar\/0e7855f89a15fccf1723a4c1e0baa027ad2d626c5d46442f8522f2338dbd8a2e?s=96&d=mm&r=g"}},{"@type":"WebPage","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#webpage","url":"https:\/\/nijar.org\/it\/rivista-marzo-2024","name":"Journal March 2024 - The Garden of N\u00e2m ~ Retreat & Meditation Center","description":"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/nijar.org\/it\/#website"},"breadcrumb":{"@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#breadcrumblist"},"author":{"@id":"https:\/\/nijar.org\/it\/author\/katrin-brait#author"},"creator":{"@id":"https:\/\/nijar.org\/it\/author\/katrin-brait#author"},"image":{"@type":"ImageObject","url":"https:\/\/nijar.org\/wp-content\/uploads\/2024\/03\/IMG_5582.jpeg","@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024\/#mainImage","width":1300,"height":975},"primaryImageOfPage":{"@id":"https:\/\/nijar.org\/it\/rivista-marzo-2024#mainImage"},"datePublished":"2024-03-06T14:05:02+01:00","dateModified":"2024-03-07T20:59:53+01:00"},{"@type":"WebSite","@id":"https:\/\/nijar.org\/it\/#website","url":"https:\/\/nijar.org\/it\/","name":"The Garden of N\u00e2m ~ Retreat & Meditation Center","description":"Meditation Centre with Guest Rooms in Andalusia","inLanguage":"it-IT","publisher":{"@id":"https:\/\/nijar.org\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"The Garden of N\u00e2m ~ Retreat &amp; Meditation Center - Meditation Centre with Guest Rooms in Andalusia","og:type":"article","og:title":"Journal March 2024 - The Garden of N\u00e2m ~ Retreat &amp; Meditation Center","og:description":"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.","og:url":"https:\/\/nijar.org\/it\/rivista-marzo-2024","og:image":"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg","og:image:secure_url":"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg","og:image:width":1500,"og:image:height":1000,"article:published_time":"2024-03-06T13:05:02+00:00","article:modified_time":"2024-03-07T19:59:53+00:00","article:publisher":"https:\/\/facebook.com\/thegardenofnam","twitter:card":"summary_large_image","twitter:title":"Journal March 2024 - The Garden of N\u00e2m ~ Retreat &amp; Meditation Center","twitter:description":"Living in the Garden of N\u00e2m Starting with strong winds and a little bit of rain, February showed the first signs of a coming spring. In the evening and in the early fresh mornings the air is still cool and a jacket is needed. During meditations and in the guest rooms stoves create a comfortable atmosphere.","twitter:image":"https:\/\/nijar.org\/wp-content\/uploads\/2024\/01\/nijar-nature.jpg"},"aioseo_meta_data":{"post_id":"7121","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":"2026-05-12 21:04:16","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-08-10 17:25:17","updated":"2026-05-12 21:04:16"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/nijar.org\/it\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale\" title=\"The Monthly Journal\">The Monthly Journal<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tJournal March 2024\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/nijar.org\/it"},{"label":"The Monthly Journal","link":"https:\/\/nijar.org\/it\/categoria\/il-mensile-giornale"},{"label":"Journal March 2024","link":"https:\/\/nijar.org\/it\/rivista-marzo-2024"}],"_links":{"self":[{"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/posts\/7121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/comments?post=7121"}],"version-history":[{"count":0,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/posts\/7121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/media\/7126"}],"wp:attachment":[{"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/media?parent=7121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/categories?post=7121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nijar.org\/it\/wp-json\/wp\/v2\/tags?post=7121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}